{"id":7,"count":0,"description":"","link":"https:\/\/portaljepara.biz.id\/baksokuah\/category\/resep\/","name":"Resep","slug":"resep","taxonomy":"category","parent":0,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.3 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Resep Archives - Bakso Kuah<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/portaljepara.biz.id\/baksokuah\/category\/resep\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Resep Archives - Bakso Kuah\" \/>\n<meta property=\"og:url\" content=\"https:\/\/portaljepara.biz.id\/baksokuah\/category\/resep\/\" \/>\n<meta property=\"og:site_name\" content=\"Bakso Kuah\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/portaljepara.biz.id\/baksokuah\/category\/resep\/\",\"url\":\"https:\/\/portaljepara.biz.id\/baksokuah\/category\/resep\/\",\"name\":\"Resep Archives - Bakso Kuah\",\"isPartOf\":{\"@id\":\"https:\/\/portaljepara.biz.id\/baksokuah\/#website\"},\"breadcrumb\":{\"@id\":\"https:\/\/portaljepara.biz.id\/baksokuah\/category\/resep\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/portaljepara.biz.id\/baksokuah\/category\/resep\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/portaljepara.biz.id\/baksokuah\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Resep\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/portaljepara.biz.id\/baksokuah\/#website\",\"url\":\"https:\/\/portaljepara.biz.id\/baksokuah\/\",\"name\":\"Bakso Kuah\",\"description\":\"Menjual Bakso Kuah Mercon, Bakso Kuah Cup, Bakso Kuah Bening, Foto Bakso Kuah,Bakso Kuah Mercon\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/portaljepara.biz.id\/baksokuah\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Resep Archives - Bakso Kuah","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/portaljepara.biz.id\/baksokuah\/category\/resep\/","og_locale":"en_US","og_type":"article","og_title":"Resep Archives - Bakso Kuah","og_url":"https:\/\/portaljepara.biz.id\/baksokuah\/category\/resep\/","og_site_name":"Bakso Kuah","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/portaljepara.biz.id\/baksokuah\/category\/resep\/","url":"https:\/\/portaljepara.biz.id\/baksokuah\/category\/resep\/","name":"Resep Archives - Bakso Kuah","isPartOf":{"@id":"https:\/\/portaljepara.biz.id\/baksokuah\/#website"},"breadcrumb":{"@id":"https:\/\/portaljepara.biz.id\/baksokuah\/category\/resep\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/portaljepara.biz.id\/baksokuah\/category\/resep\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/portaljepara.biz.id\/baksokuah\/"},{"@type":"ListItem","position":2,"name":"Resep"}]},{"@type":"WebSite","@id":"https:\/\/portaljepara.biz.id\/baksokuah\/#website","url":"https:\/\/portaljepara.biz.id\/baksokuah\/","name":"Bakso Kuah","description":"Menjual Bakso Kuah Mercon, Bakso Kuah Cup, Bakso Kuah Bening, Foto Bakso Kuah,Bakso Kuah Mercon","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/portaljepara.biz.id\/baksokuah\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/portaljepara.biz.id\/baksokuah\/wp-json\/wp\/v2\/categories\/7","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/portaljepara.biz.id\/baksokuah\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/portaljepara.biz.id\/baksokuah\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/portaljepara.biz.id\/baksokuah\/wp-json\/wp\/v2\/posts?categories=7"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}