{"id":102,"date":"2025-12-28T04:42:37","date_gmt":"2025-12-28T04:42:37","guid":{"rendered":"https:\/\/portaljepara.biz.id\/esteh\/?p=102"},"modified":"2025-12-28T04:42:37","modified_gmt":"2025-12-28T04:42:37","slug":"lychee-tea","status":"publish","type":"post","link":"https:\/\/portaljepara.biz.id\/esteh\/2025\/12\/28\/lychee-tea\/","title":{"rendered":"Lychee Tea"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter\" src=\"https:\/\/i.pinimg.com\/736x\/dd\/e3\/d5\/dde3d5f1131a204785d0ef328eb9014b.jpg\" alt=\"es teh leci | Teh manis, Teh, Teh susu\" width=\"113\" height=\"201\" \/><\/p>\n<p data-start=\"73\" data-end=\"373\"><strong>Lychee tea<\/strong> adalah minuman segar dengan rasa manis alami buah leci yang juicy dan aromanya khas. Setiap tegukan kasih sensasi fresh yang ringan, nggak bikin enek, dan langsung bikin haus auto hilang. Perpaduan teh yang smooth dengan leci yang fruity bikin rasanya balance\u2014manisnya pas, segarnya dapet.<\/p>\n<p data-start=\"375\" data-end=\"584\">Cocok diminum siang hari pas panas, nemenin nugas, nongkrong, atau sekadar break bentar dari rutinitas. Disajikan dingin dengan es batu, lychee tea jadi minuman favorit yang nggak pernah gagal bikin mood naik.<\/p>\n<p data-start=\"586\" data-end=\"696\">Simple tapi nagih\u2014<strong>lychee tea<\/strong> itu definisi minuman segar yang selalu jadi pilihan aman buat semua suasana<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Lychee tea adalah minuman segar dengan rasa manis alami buah leci yang juicy dan aromanya khas. Setiap tegukan kasih sensasi fresh yang ringan, nggak bikin enek, dan langsung [&hellip;]<\/p>\n","protected":false},"author":126,"featured_media":103,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[2],"tags":[],"class_list":["post-102","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-produk"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.3 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Lychee Tea - Es Teh<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/portaljepara.biz.id\/esteh\/2025\/12\/28\/lychee-tea\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Lychee Tea - Es Teh\" \/>\n<meta property=\"og:description\" content=\"Lychee tea adalah minuman segar dengan rasa manis alami buah leci yang juicy dan aromanya khas. Setiap tegukan kasih sensasi fresh yang ringan, nggak bikin enek, dan langsung [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/portaljepara.biz.id\/esteh\/2025\/12\/28\/lychee-tea\/\" \/>\n<meta property=\"og:site_name\" content=\"Es Teh\" \/>\n<meta property=\"article:published_time\" content=\"2025-12-28T04:42:37+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/portaljepara.biz.id\/esteh\/wp-content\/uploads\/sites\/126\/2025\/12\/dde3d5f1131a204785d0ef328eb9014b.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"720\" \/>\n\t<meta property=\"og:image:height\" content=\"1280\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"esteh\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"esteh\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/portaljepara.biz.id\/esteh\/2025\/12\/28\/lychee-tea\/\",\"url\":\"https:\/\/portaljepara.biz.id\/esteh\/2025\/12\/28\/lychee-tea\/\",\"name\":\"Lychee Tea - Es Teh\",\"isPartOf\":{\"@id\":\"https:\/\/portaljepara.biz.id\/esteh\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/portaljepara.biz.id\/esteh\/2025\/12\/28\/lychee-tea\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/portaljepara.biz.id\/esteh\/2025\/12\/28\/lychee-tea\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/portaljepara.biz.id\/esteh\/wp-content\/uploads\/sites\/126\/2025\/12\/dde3d5f1131a204785d0ef328eb9014b.jpg\",\"datePublished\":\"2025-12-28T04:42:37+00:00\",\"author\":{\"@id\":\"https:\/\/portaljepara.biz.id\/esteh\/#\/schema\/person\/9a56b64f1398175507fb632b402e5a05\"},\"breadcrumb\":{\"@id\":\"https:\/\/portaljepara.biz.id\/esteh\/2025\/12\/28\/lychee-tea\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/portaljepara.biz.id\/esteh\/2025\/12\/28\/lychee-tea\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/portaljepara.biz.id\/esteh\/2025\/12\/28\/lychee-tea\/#primaryimage\",\"url\":\"https:\/\/portaljepara.biz.id\/esteh\/wp-content\/uploads\/sites\/126\/2025\/12\/dde3d5f1131a204785d0ef328eb9014b.jpg\",\"contentUrl\":\"https:\/\/portaljepara.biz.id\/esteh\/wp-content\/uploads\/sites\/126\/2025\/12\/dde3d5f1131a204785d0ef328eb9014b.jpg\",\"width\":720,\"height\":1280},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/portaljepara.biz.id\/esteh\/2025\/12\/28\/lychee-tea\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/portaljepara.biz.id\/esteh\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Lychee Tea\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/portaljepara.biz.id\/esteh\/#website\",\"url\":\"https:\/\/portaljepara.biz.id\/esteh\/\",\"name\":\"Es Teh\",\"description\":\"Logo Es Teh, Es Teh png ,Es Teh Indonesia ,Es Teh Hijau,Es Teh Manis ,Es Teh Solo,Gambar Es Teh ,Es Teh Cup ,Es Teh Jumbo ,Es Teh Poci\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/portaljepara.biz.id\/esteh\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/portaljepara.biz.id\/esteh\/#\/schema\/person\/9a56b64f1398175507fb632b402e5a05\",\"name\":\"esteh\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/portaljepara.biz.id\/esteh\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/922f84d8df1422a265dee62a3ff99f4f4407bb1b7a1ce6c3319e9c3c58877b22?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/922f84d8df1422a265dee62a3ff99f4f4407bb1b7a1ce6c3319e9c3c58877b22?s=96&d=mm&r=g\",\"caption\":\"esteh\"},\"url\":\"https:\/\/portaljepara.biz.id\/esteh\/author\/esteh\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Lychee Tea - Es Teh","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/portaljepara.biz.id\/esteh\/2025\/12\/28\/lychee-tea\/","og_locale":"en_US","og_type":"article","og_title":"Lychee Tea - Es Teh","og_description":"Lychee tea adalah minuman segar dengan rasa manis alami buah leci yang juicy dan aromanya khas. Setiap tegukan kasih sensasi fresh yang ringan, nggak bikin enek, dan langsung [&hellip;]","og_url":"https:\/\/portaljepara.biz.id\/esteh\/2025\/12\/28\/lychee-tea\/","og_site_name":"Es Teh","article_published_time":"2025-12-28T04:42:37+00:00","og_image":[{"width":720,"height":1280,"url":"https:\/\/portaljepara.biz.id\/esteh\/wp-content\/uploads\/sites\/126\/2025\/12\/dde3d5f1131a204785d0ef328eb9014b.jpg","type":"image\/jpeg"}],"author":"esteh","twitter_card":"summary_large_image","twitter_misc":{"Written by":"esteh","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/portaljepara.biz.id\/esteh\/2025\/12\/28\/lychee-tea\/","url":"https:\/\/portaljepara.biz.id\/esteh\/2025\/12\/28\/lychee-tea\/","name":"Lychee Tea - Es Teh","isPartOf":{"@id":"https:\/\/portaljepara.biz.id\/esteh\/#website"},"primaryImageOfPage":{"@id":"https:\/\/portaljepara.biz.id\/esteh\/2025\/12\/28\/lychee-tea\/#primaryimage"},"image":{"@id":"https:\/\/portaljepara.biz.id\/esteh\/2025\/12\/28\/lychee-tea\/#primaryimage"},"thumbnailUrl":"https:\/\/portaljepara.biz.id\/esteh\/wp-content\/uploads\/sites\/126\/2025\/12\/dde3d5f1131a204785d0ef328eb9014b.jpg","datePublished":"2025-12-28T04:42:37+00:00","author":{"@id":"https:\/\/portaljepara.biz.id\/esteh\/#\/schema\/person\/9a56b64f1398175507fb632b402e5a05"},"breadcrumb":{"@id":"https:\/\/portaljepara.biz.id\/esteh\/2025\/12\/28\/lychee-tea\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/portaljepara.biz.id\/esteh\/2025\/12\/28\/lychee-tea\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/portaljepara.biz.id\/esteh\/2025\/12\/28\/lychee-tea\/#primaryimage","url":"https:\/\/portaljepara.biz.id\/esteh\/wp-content\/uploads\/sites\/126\/2025\/12\/dde3d5f1131a204785d0ef328eb9014b.jpg","contentUrl":"https:\/\/portaljepara.biz.id\/esteh\/wp-content\/uploads\/sites\/126\/2025\/12\/dde3d5f1131a204785d0ef328eb9014b.jpg","width":720,"height":1280},{"@type":"BreadcrumbList","@id":"https:\/\/portaljepara.biz.id\/esteh\/2025\/12\/28\/lychee-tea\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/portaljepara.biz.id\/esteh\/"},{"@type":"ListItem","position":2,"name":"Lychee Tea"}]},{"@type":"WebSite","@id":"https:\/\/portaljepara.biz.id\/esteh\/#website","url":"https:\/\/portaljepara.biz.id\/esteh\/","name":"Es Teh","description":"Logo Es Teh, Es Teh png ,Es Teh Indonesia ,Es Teh Hijau,Es Teh Manis ,Es Teh Solo,Gambar Es Teh ,Es Teh Cup ,Es Teh Jumbo ,Es Teh Poci","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/portaljepara.biz.id\/esteh\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/portaljepara.biz.id\/esteh\/#\/schema\/person\/9a56b64f1398175507fb632b402e5a05","name":"esteh","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/portaljepara.biz.id\/esteh\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/922f84d8df1422a265dee62a3ff99f4f4407bb1b7a1ce6c3319e9c3c58877b22?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/922f84d8df1422a265dee62a3ff99f4f4407bb1b7a1ce6c3319e9c3c58877b22?s=96&d=mm&r=g","caption":"esteh"},"url":"https:\/\/portaljepara.biz.id\/esteh\/author\/esteh\/"}]}},"_links":{"self":[{"href":"https:\/\/portaljepara.biz.id\/esteh\/wp-json\/wp\/v2\/posts\/102","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/portaljepara.biz.id\/esteh\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/portaljepara.biz.id\/esteh\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/portaljepara.biz.id\/esteh\/wp-json\/wp\/v2\/users\/126"}],"replies":[{"embeddable":true,"href":"https:\/\/portaljepara.biz.id\/esteh\/wp-json\/wp\/v2\/comments?post=102"}],"version-history":[{"count":1,"href":"https:\/\/portaljepara.biz.id\/esteh\/wp-json\/wp\/v2\/posts\/102\/revisions"}],"predecessor-version":[{"id":104,"href":"https:\/\/portaljepara.biz.id\/esteh\/wp-json\/wp\/v2\/posts\/102\/revisions\/104"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/portaljepara.biz.id\/esteh\/wp-json\/wp\/v2\/media\/103"}],"wp:attachment":[{"href":"https:\/\/portaljepara.biz.id\/esteh\/wp-json\/wp\/v2\/media?parent=102"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/portaljepara.biz.id\/esteh\/wp-json\/wp\/v2\/categories?post=102"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/portaljepara.biz.id\/esteh\/wp-json\/wp\/v2\/tags?post=102"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}